{"id":27733,"date":"2008-11-09T07:00:00","date_gmt":"2008-11-09T07:00:00","guid":{"rendered":"https:\/\/intlweloveu.org\/9th-new-life-concert\/"},"modified":"2026-01-23T07:51:03","modified_gmt":"2026-01-23T07:51:03","slug":"9th-new-life-concert","status":"publish","type":"post","link":"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/","title":{"rendered":"9.\u00ba Concierto Nueva Vida"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_02.jpg\" alt=\"\" class=\"wp-image-27699\" srcset=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_02.jpg 1920w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_02-768x512.jpg 768w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_02-1536x1024.jpg 1536w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_02-750x500.jpg 750w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cMis ojos se llenan de l\u00e1grimas cada vez que canto en este concierto. Es porque siento su amor.\u201d<\/p>\n<\/blockquote>\n<p class=\"wp-block-paragraph\">El cantante Yun Tae-gyu salud\u00f3 profundamente emocionado a la audiencia que incluso llenaba los pasillos. \u00c9l cancel\u00f3 sus dem\u00e1s compromisos para presentarse en este concierto, y la mayor\u00eda de los dem\u00e1s cantantes tambi\u00e9n participaron en el concierto realizado por la Fundaci\u00f3n Internacional WeLoveU, ofreciendo voluntariamente sus talentos a lo largo de los a\u00f1os. \u201cEstoy muy feliz de ayudar a la gente con mi canci\u00f3n\u201d, dijo Lee Seung-hun. \u201cEl amor que recibo aqu\u00ed es la energ\u00eda para que viva todo el a\u00f1o\u201d, declar\u00f3 Baek Mi-hyeon. \u201cCada vez que participo en este concierto, siento que el amor crece cada vez m\u00e1s en mi coraz\u00f3n\u201d, dijo Sunflower. Todos los cantantes ofrecieron a la audiencia interpretaciones apasionadas con voces llenas de emoci\u00f3n.<\/p>\n<p class=\"wp-block-paragraph\">El 9 de noviembre de 2008, la Fundaci\u00f3n Internacional WeLoveU realiz\u00f3 con gran \u00e9xito el 9.\u00ba Concierto Nueva Vida en el Gimnasio de Estudiantes Jamsil de Se\u00fal, con m\u00e1s de diez mil asistentes, para ayudar a los ni\u00f1os que sufren enfermedades y al pr\u00f3jimo en necesidad. Este evento fue auspiciado por el Ministerio de Salud, Bienestar y Asuntos Familiares, la ciudad de Se\u00fal, el Centro de Servicio Juvenil Coreano y el Hospital General Sejong en Bucheon. Muchas celebridades asistieron al concierto: Zahng Gil-jah, Presidenta de la Fundaci\u00f3n Internacional WeLoveU, Lee Kang-min, Director General de la fundaci\u00f3n, Lee Soon-jae, Patrocinador Principal de la fundaci\u00f3n, Kim Gu-seob, jefe del Instituto Coreano de An\u00e1lisis de Defensa, Yi Bae-keun, director del Centro de Servicio Juvenil Coreano, Lydie Bertrand, funcionaria de informaci\u00f3n de la embajada de Francia en Corea, Harry A. C. van Woerden, jefe de la Agencia de Inversiones Extranjeras de los Pa\u00edses Bajos en Corea, adem\u00e1s de los embajadores de Relaciones P\u00fablicas de la fundaci\u00f3n, Kim Ji-yu (actriz), Lee Seung-hun (cantante), Kim Bo-seong (actor) y Han Wang-young (monta\u00f1ista).<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"27700\" src=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_03.jpg\" alt=\"\" class=\"wp-image-27700\" srcset=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_03.jpg 1170w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_03-768x361.jpg 768w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_03-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"27701\" src=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_04.jpg\" alt=\"\" class=\"wp-image-27701\" srcset=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_04.jpg 1170w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_04-768x361.jpg 768w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_04-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<\/figure>\n<p class=\"wp-block-paragraph\">La ceremonia de entrega de la donaci\u00f3n se inici\u00f3 a las 3:30 p. m. La Presidenta Zahng Gil-jah anim\u00f3 a los beneficiarios que viv\u00edan sin perder la esperanza incluso en dificultades, y tambi\u00e9n expres\u00f3 su gratitud a los miembros de la fundaci\u00f3n que compartieron amor con el pr\u00f3jimo desafortunado a pesar de la recesi\u00f3n econ\u00f3mica. \u201cLa manera de vivir de las personas se refleja en sus rostros. Hoy, ustedes se ven hermosos como los \u00e1ngeles. Esto demuestra que han llevado vidas hermosas\u201d, manifest\u00f3. Ella tambi\u00e9n enfatiz\u00f3 que la vida m\u00e1s hermosa es ser considerado y compartir lo que tenemos con los dem\u00e1s. El Patrocinador Principal Lee Soon-jae entreg\u00f3 esperanza y valor a los participantes, diciendo: \u201cLas enfermedades card\u00edacas y la leucemia no son enfermedades incurables. Si nos preocupamos m\u00e1s y apoyamos a los ni\u00f1os para que se sanen, de ellos saldr\u00e1n grandes personalidades que contribuir\u00e1n con la comunidad y el pa\u00eds\u201d.<\/p>\n<p class=\"wp-block-paragraph\">Kim Gu-seob, jefe del Instituto Coreano de An\u00e1lisis de Defensa, mostr\u00f3 su agradecimiento por los esfuerzos de la Fundaci\u00f3n Internacional WeLoveU que transmiti\u00f3 el amor de una madre a la aldea global que estaba en peligro debido al hambre y los conflictos entre naciones. \u00c9l dijo: \u201cEl lugar m\u00e1s c\u00f3modo y seguro para la gente es los brazos de sus madres\u201d. Yi Bae-keun, director del Centro de Servicio Juvenil Coreano, enfatiz\u00f3 el amor de una madre, diciendo: \u201cAlimentar a los hambrientos y curar a los enfermos, independientemente de la clase social, riqueza o pobreza, raza y formaci\u00f3n, es el amor de una madre\u201d. Tambi\u00e9n elogi\u00f3 a los miembros de la fundaci\u00f3n que sembraron las semillas de amor de una madre en todo el mundo, que es lo m\u00e1s hermoso y eterno en el mundo, y bendijo para que las semillas broten y lleven hermosos frutos abundantemente. Lydie Bertrand, funcionaria de informaci\u00f3n de la embajada de Francia en Corea, ley\u00f3 la carta de felicitaci\u00f3n del embajador Philippe Thiebaud, quien estuvo de acuerdo con el principio de compartir amor de la Fundaci\u00f3n Internacional WeLoveU y dese\u00f3 el desarrollo indefinido de la fundaci\u00f3n. Harry A.C. van Woerden, jefe de la Agencia de Inversiones Extranjeras de los Pa\u00edses Bajo en Corea, dijo reiteradamente: \u201cEstoy muy feliz. Los amo\u201d. Y dese\u00f3 que esta mano de ayuda llegue a todos los ni\u00f1os del mundo.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"27702\" src=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_05.jpg\" alt=\"\" class=\"wp-image-27702\" srcset=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_05.jpg 1170w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_05-768x361.jpg 768w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_05-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"27703\" src=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_06.jpg\" alt=\"\" class=\"wp-image-27703\" srcset=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_06.jpg 1170w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_06-768x361.jpg 768w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_06-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<\/figure>\n<p class=\"wp-block-paragraph\">Despu\u00e9s de un mensaje de felicitaci\u00f3n de las celebridades, se entregaron donaciones y regalos sinceros a 34 personas necesitadas: ni\u00f1os que sufren de enfermedades card\u00edacas, leucemia y enfermedades raras, familias multiculturales necesitadas, ni\u00f1os que viven con sus abuelos, familias monoparentales y tambi\u00e9n a los experimentados cantantes Myeong Guk-hwan y Keum Sa-hyang. Los miembros de la fundaci\u00f3n los animaron con una gran ronda de aplausos.<\/p>\n<p class=\"wp-block-paragraph\">El concierto comenz\u00f3 despu\u00e9s de la ceremonia de entrega de donaci\u00f3n. El Coro Infantil Nueva Vida, los cantantes Yun Tae-gyu, Baek Mi-hyeon, Lee Seung-hun, Kim Gyu-min, Kim Je-hun, Kim Bo-seong, Eom Tae-gyeong, la banda de rock Aktung y el d\u00fao Sunflower entregaron el mensaje de amor, entonando canciones de amor. Como invitados especiales, algunos ni\u00f1os extranjeros de la Escuela de Extranjeros de Se\u00fal interpretaron canciones y la danza del hula. La audiencia anim\u00f3 a los cantantes, aplaudiendo y agitando las manos con sus tel\u00e9fonos m\u00f3viles. Junto con la ola de luces parpadeantes, los benefactores y beneficiarios se unieron en amor.<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cEn Corea, he sufrido mucho, pero hoy he comprendido que hay muchas personas que est\u00e1n realizando buenas obras.\u201d<\/p>\n<\/blockquote>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cNo sab\u00eda que tantas personas estaban haciendo buenas cosas. Hasta ahora solo hab\u00eda recibido ayuda, pero a partir de ahora me gustar\u00eda participar con ellos y hacer el bien para los dem\u00e1s.\u201d<\/p>\n<\/blockquote>\n<p class=\"wp-block-paragraph\">Cuando termin\u00f3 el concierto, floreci\u00f3 una sonrisa en los rostros de la madre de Gyeong-ryun, quien hab\u00eda llevado una vida dura f\u00edsica y mentalmente como coreana-china, y de la madre de Jong-wong, quien se sent\u00eda desconsolada por su hijo que sufr\u00eda de leucemia. Durante el concierto todos los participantes estaban llenos de sonrisas felices, y nuestro pr\u00f3jimo que hab\u00eda sufrido ahora estaba hablando de esperanza y gratitud, dejando atr\u00e1s todos los recuerdos dolorosos. Cantando juntos las canciones\u00a0<em>En el amor<\/em>\u00a0y\u00a0<em>Si todos somos \u00e1ngeles<\/em>, los \u00e1ngeles que dan amor y los angelitos que reciben amor volvieron muy c\u00e1lido el mundo fr\u00edo, hasta terminar el 9.o Concierto Nueva Vida.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"27704\" src=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_07.jpg\" alt=\"\" class=\"wp-image-27704\" srcset=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_07.jpg 1170w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_07-768x361.jpg 768w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_07-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" data-id=\"27705\" src=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_08.jpg\" alt=\"\" class=\"wp-image-27705\" srcset=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_08.jpg 1920w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_08-768x512.jpg 768w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_08-1536x1024.jpg 1536w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_08-750x500.jpg 750w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1275\" data-id=\"27706\" src=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_09.jpg\" alt=\"\" class=\"wp-image-27706\" srcset=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_09.jpg 1920w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_09-768x510.jpg 768w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_09-1536x1020.jpg 1536w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_09-753x500.jpg 753w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"27707\" src=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_10.jpg\" alt=\"\" class=\"wp-image-27707\" srcset=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_10.jpg 1170w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_10-768x361.jpg 768w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_10-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"\u201cMis ojos se llenan de l\u00e1grimas cada vez que canto en este concierto. Es porque siento su amor.\u201d El cantante Yun Tae-gyu salud\u00f3 profundamente emocionado a la audiencia que incluso llenaba los pasillos. \u00c9l cancel\u00f3 sus dem\u00e1s compromisos para presentarse en este concierto, y la mayor\u00eda de los dem\u00e1s cantantes tambi\u00e9n participaron en el concierto&#8230;","protected":false},"author":11,"featured_media":27729,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,93,73,110],"tags":[],"class_list":["post-27733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sdgs","category-concert","category-campaign-news","category-sdgs-peace"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>9.\u00ba Concierto Nueva Vida - Fundaci\u00f3n Internacional WeLoveU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9.\u00ba Concierto Nueva Vida - Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"og:description\" content=\"\u201cMis ojos se llenan de l\u00e1grimas cada vez que canto en este concierto. Es porque siento su amor.\u201d El cantante Yun Tae-gyu salud\u00f3 profundamente emocionado a la audiencia que incluso llenaba los pasillos. \u00c9l cancel\u00f3 sus dem\u00e1s compromisos para presentarse en este concierto, y la mayor\u00eda de los dem\u00e1s cantantes tambi\u00e9n participaron en el concierto...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"article:published_time\" content=\"2008-11-09T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T07:51:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"l ss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"l ss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/\",\"url\":\"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/\",\"name\":\"9.\u00ba Concierto Nueva Vida - Fundaci\u00f3n Internacional WeLoveU\",\"isPartOf\":{\"@id\":\"https:\/\/test.intlweloveu.org\/ko\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_01.jpg\",\"datePublished\":\"2008-11-09T07:00:00+00:00\",\"dateModified\":\"2026-01-23T07:51:03+00:00\",\"author\":{\"@id\":\"https:\/\/test.intlweloveu.org\/ko\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131\"},\"breadcrumb\":{\"@id\":\"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/#primaryimage\",\"url\":\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_01.jpg\",\"contentUrl\":\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_01.jpg\",\"width\":1920,\"height\":1275},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ud648\",\"item\":\"https:\/\/test.intlweloveu.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"9.\u00ba Concierto Nueva Vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/test.intlweloveu.org\/ko\/#website\",\"url\":\"https:\/\/test.intlweloveu.org\/ko\/\",\"name\":\"Fundaci\u00f3n Internacional WeLoveU\",\"description\":\"El Amor de la Madre al Mundo Entero\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/test.intlweloveu.org\/ko\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/test.intlweloveu.org\/ko\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131\",\"name\":\"l ss\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"9.\u00ba Concierto Nueva Vida - Fundaci\u00f3n Internacional WeLoveU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/","og_locale":"es_ES","og_type":"article","og_title":"9.\u00ba Concierto Nueva Vida - Fundaci\u00f3n Internacional WeLoveU","og_description":"\u201cMis ojos se llenan de l\u00e1grimas cada vez que canto en este concierto. Es porque siento su amor.\u201d El cantante Yun Tae-gyu salud\u00f3 profundamente emocionado a la audiencia que incluso llenaba los pasillos. \u00c9l cancel\u00f3 sus dem\u00e1s compromisos para presentarse en este concierto, y la mayor\u00eda de los dem\u00e1s cantantes tambi\u00e9n participaron en el concierto...","og_url":"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/","og_site_name":"Fundaci\u00f3n Internacional WeLoveU","article_published_time":"2008-11-09T07:00:00+00:00","article_modified_time":"2026-01-23T07:51:03+00:00","og_image":[{"width":1920,"height":1275,"url":"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_01.jpg","type":"image\/jpeg"}],"author":"l ss","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"l ss","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/","url":"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/","name":"9.\u00ba Concierto Nueva Vida - Fundaci\u00f3n Internacional WeLoveU","isPartOf":{"@id":"https:\/\/test.intlweloveu.org\/ko\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/#primaryimage"},"image":{"@id":"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/#primaryimage"},"thumbnailUrl":"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_01.jpg","datePublished":"2008-11-09T07:00:00+00:00","dateModified":"2026-01-23T07:51:03+00:00","author":{"@id":"https:\/\/test.intlweloveu.org\/ko\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131"},"breadcrumb":{"@id":"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/#primaryimage","url":"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_01.jpg","contentUrl":"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_9th_new_life_concert_01.jpg","width":1920,"height":1275},{"@type":"BreadcrumbList","@id":"https:\/\/test.intlweloveu.org\/es\/9th-new-life-concert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ud648","item":"https:\/\/test.intlweloveu.org\/es\/"},{"@type":"ListItem","position":2,"name":"9.\u00ba Concierto Nueva Vida"}]},{"@type":"WebSite","@id":"https:\/\/test.intlweloveu.org\/ko\/#website","url":"https:\/\/test.intlweloveu.org\/ko\/","name":"Fundaci\u00f3n Internacional WeLoveU","description":"El Amor de la Madre al Mundo Entero","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.intlweloveu.org\/ko\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/test.intlweloveu.org\/ko\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131","name":"l ss"}]}},"_links":{"self":[{"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/27733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/comments?post=27733"}],"version-history":[{"count":3,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/27733\/revisions"}],"predecessor-version":[{"id":232945,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/27733\/revisions\/232945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/media\/27729"}],"wp:attachment":[{"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/media?parent=27733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/categories?post=27733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/tags?post=27733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}