{"id":42043,"date":"2022-08-22T07:00:00","date_gmt":"2022-08-22T07:00:00","guid":{"rendered":"https:\/\/intlweloveu.org\/national-assembly-ecuador-award-220822\/"},"modified":"2025-11-17T11:43:59","modified_gmt":"2025-11-17T11:43:59","slug":"national-assembly-ecuador-award-220822","status":"publish","type":"post","link":"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/","title":{"rendered":"Fundaci\u00f3n Internacional WeLoveU honrada con el Premio de la Asamblea Nacional del Ecuador"},"content":{"rendered":"<figure class=\"wp-block-image size-full limit\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_01.jpg\" alt=\"\" class=\"wp-image-42024\" srcset=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_01.jpg 1080w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_01-768x480.jpg 768w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_01-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">El 18 de julio, la Fundaci\u00f3n Internacional WeLoveU (en adelante WeLoveU) recibi\u00f3 la medalla Asamblea Nacional de la Rep\u00fablica del Ecuador, \u201cDr. Vicente Rocafuerte\u201d. La medalla \u201cDr. Vicente Rocafuerte\u201d es la medalla m\u00e1s honorable en el \u00e1mbito de la contribuci\u00f3n social, otorgada por la\u00a0<a href=\"https:\/\/www.asambleanacional.gob.ec\/es\" target=\"_blank\" rel=\"noreferrer noopener\">Asamblea Nacional del Ecuador<\/a>. Solo las organizaciones que han realizado contribuciones destacadas que se puedan verificar en los campos de la pol\u00edtica, la cultura, la educaci\u00f3n, los negocios, la econom\u00eda, el trabajo, la sociedad y el deporte, son premiadas con la recomendaci\u00f3n de un miembro de la Asamblea Nacional o del alcalde de cada gobierno local o departamento gubernamental. Si se demuestra que han hecho una contribuci\u00f3n destacada al mejoramiento nacional, los ganadores se determinan mediante la aprobaci\u00f3n del Presidente de la Asamblea Nacional.<\/p>\n<figure class=\"wp-block-image size-full limit\"><img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"393\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_02.jpg\" alt=\"\" class=\"wp-image-42025\"\/><\/figure>\n<p class=\"wp-block-paragraph\">Para el terremoto en Ecuador en 2016, WeLoveU don\u00f3 art\u00edculos de primera necesidad a 644 hogares recaudando fondos valorizados en 50 000 d\u00f3lares a trav\u00e9s de la\u00a0<a href=\"https:\/\/intlweloveu.org\/es\/17th-newlife-family-walk\/\" target=\"_blank\" rel=\"noreferrer noopener\">17.\u00aa Caminata Familiar Nueva Vida<\/a>. En 2017, donaron \u00fatiles escolares a la Escuela Primaria Pablo Neruda. Entre 2020 y 2021 donaron materiales de seguridad contra la COVID-19. Tambi\u00e9n proporcionaron\u00a0<a href=\"\/es\/disaster-relief-victims-ecuador-220418\" target=\"_blank\" rel=\"noreferrer noopener\">suministros de emergencia a 500 hogares damnificados por las inundaciones en 2022<\/a>. Adem\u00e1s, durante diez a\u00f1os desde 2012, han realizado servicios voluntarios como limpiezas ambientales y campa\u00f1as de donaci\u00f3n de sangre en cooperaci\u00f3n con las oficinas del gobierno ecuatoriano.<\/p>\n<figure class=\"wp-block-image size-full limit\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_03.jpg\" alt=\"\" class=\"wp-image-42026\" srcset=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_03.jpg 1080w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_03-768x480.jpg 768w, https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_03-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">La ceremonia de entrega de premios se llev\u00f3 a cabo dos veces el 17 y 22 de agosto, en el Capitolio de Quito, Ecuador.&nbsp;<a href=\"https:\/\/www.asambleanacional.gob.ec\/es\/blogs\/virgilio-saquicela\" target=\"_blank\" rel=\"noreferrer noopener\">Virgilio Saquicela Espinoza<\/a>, Presidente de la Asamblea Nacional, entreg\u00f3 la medalla en la oficina de la Asamblea Nacional el d\u00eda 17, y dijo: \u201cMe gustar\u00eda agradecer a su organizaci\u00f3n por apoyar a nuestro pa\u00eds durante los \u00faltimos diez a\u00f1os, incluida la ayuda por el terremoto y la pandemia de la COVID-19, y la innumerable ayuda que han brindado al Ecuador\u201d. El 22 de agosto, la asamble\u00edsta Ana Cecilia Herrera G\u00f3mez, quien asisti\u00f3 a la ceremonia realizada en el sal\u00f3n principal del Capitolio, dijo: \u201cLa medalla \u201cDr. Vicente Rocafuerte\u201d es otorgada por la Asamblea Nacional del Ecuador de una manera muy especial, solo para aquellos que han logrado resultados sobresalientes. Siempre que los ecuatorianos enfrentaron dificultades, ustedes vinieron a ayudar. No podemos evitar reconocer su enorme ayuda para nosotros\u201d.<\/p>\n<p class=\"wp-block-paragraph\">Choi Jeong-woo, jefe de la sucursal de la Fundaci\u00f3n Internacional WeLoveU en Quito, recibi\u00f3 la medalla y dijo: \u201cLe entregar\u00e9 el amor de una madre a los vecinos ecuatorianos que est\u00e1n luchando con los actuales asuntos internacionales y dificultades econ\u00f3micas\u201d.<\/p>\n<p class=\"wp-block-paragraph\">\n","protected":false},"excerpt":{"rendered":"El 18 de julio, la Fundaci\u00f3n Internacional WeLoveU (en adelante WeLoveU) recibi\u00f3 la medalla Asamblea Nacional de la Rep\u00fablica del Ecuador, \u201cDr. Vicente Rocafuerte\u201d. La medalla \u201cDr. Vicente Rocafuerte\u201d es la medalla m\u00e1s honorable en el \u00e1mbito de la contribuci\u00f3n social, otorgada por la\u00a0Asamblea Nacional del Ecuador. Solo las organizaciones que han realizado contribuciones destacadas&#8230;","protected":false},"author":11,"featured_media":42292,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,58],"tags":[],"class_list":["post-42043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-global-partnership","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fundaci\u00f3n Internacional WeLoveU honrada con el Premio de la Asamblea Nacional del Ecuador - Fundaci\u00f3n Internacional WeLoveU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fundaci\u00f3n Internacional WeLoveU honrada con el Premio de la Asamblea Nacional del Ecuador - Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"og:description\" content=\"El 18 de julio, la Fundaci\u00f3n Internacional WeLoveU (en adelante WeLoveU) recibi\u00f3 la medalla Asamblea Nacional de la Rep\u00fablica del Ecuador, \u201cDr. Vicente Rocafuerte\u201d. La medalla \u201cDr. Vicente Rocafuerte\u201d es la medalla m\u00e1s honorable en el \u00e1mbito de la contribuci\u00f3n social, otorgada por la\u00a0Asamblea Nacional del Ecuador. Solo las organizaciones que han realizado contribuciones destacadas...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-22T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-17T11:43:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"l ss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"l ss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/\",\"url\":\"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/\",\"name\":\"Fundaci\u00f3n Internacional WeLoveU honrada con el Premio de la Asamblea Nacional del Ecuador - Fundaci\u00f3n Internacional WeLoveU\",\"isPartOf\":{\"@id\":\"https:\/\/test.intlweloveu.org\/ko\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_01.jpg\",\"datePublished\":\"2022-08-22T07:00:00+00:00\",\"dateModified\":\"2025-11-17T11:43:59+00:00\",\"author\":{\"@id\":\"https:\/\/test.intlweloveu.org\/ko\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131\"},\"breadcrumb\":{\"@id\":\"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/#primaryimage\",\"url\":\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_01.jpg\",\"contentUrl\":\"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_01.jpg\",\"width\":1080,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ud648\",\"item\":\"https:\/\/test.intlweloveu.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fundaci\u00f3n Internacional WeLoveU honrada con el Premio de la Asamblea Nacional del Ecuador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/test.intlweloveu.org\/ko\/#website\",\"url\":\"https:\/\/test.intlweloveu.org\/ko\/\",\"name\":\"Fundaci\u00f3n Internacional WeLoveU\",\"description\":\"El Amor de la Madre al Mundo Entero\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/test.intlweloveu.org\/ko\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/test.intlweloveu.org\/ko\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131\",\"name\":\"l ss\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fundaci\u00f3n Internacional WeLoveU honrada con el Premio de la Asamblea Nacional del Ecuador - Fundaci\u00f3n Internacional WeLoveU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/","og_locale":"es_ES","og_type":"article","og_title":"Fundaci\u00f3n Internacional WeLoveU honrada con el Premio de la Asamblea Nacional del Ecuador - Fundaci\u00f3n Internacional WeLoveU","og_description":"El 18 de julio, la Fundaci\u00f3n Internacional WeLoveU (en adelante WeLoveU) recibi\u00f3 la medalla Asamblea Nacional de la Rep\u00fablica del Ecuador, \u201cDr. Vicente Rocafuerte\u201d. La medalla \u201cDr. Vicente Rocafuerte\u201d es la medalla m\u00e1s honorable en el \u00e1mbito de la contribuci\u00f3n social, otorgada por la\u00a0Asamblea Nacional del Ecuador. Solo las organizaciones que han realizado contribuciones destacadas...","og_url":"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/","og_site_name":"Fundaci\u00f3n Internacional WeLoveU","article_published_time":"2022-08-22T07:00:00+00:00","article_modified_time":"2025-11-17T11:43:59+00:00","og_image":[{"width":1080,"height":675,"url":"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_01.jpg","type":"image\/jpeg"}],"author":"l ss","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"l ss","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/","url":"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/","name":"Fundaci\u00f3n Internacional WeLoveU honrada con el Premio de la Asamblea Nacional del Ecuador - Fundaci\u00f3n Internacional WeLoveU","isPartOf":{"@id":"https:\/\/test.intlweloveu.org\/ko\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/#primaryimage"},"image":{"@id":"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/#primaryimage"},"thumbnailUrl":"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_01.jpg","datePublished":"2022-08-22T07:00:00+00:00","dateModified":"2025-11-17T11:43:59+00:00","author":{"@id":"https:\/\/test.intlweloveu.org\/ko\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131"},"breadcrumb":{"@id":"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/#primaryimage","url":"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_01.jpg","contentUrl":"https:\/\/test.intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_national_assembly_ecuador_award_220822_01.jpg","width":1080,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/test.intlweloveu.org\/es\/national-assembly-ecuador-award-220822\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ud648","item":"https:\/\/test.intlweloveu.org\/es\/"},{"@type":"ListItem","position":2,"name":"Fundaci\u00f3n Internacional WeLoveU honrada con el Premio de la Asamblea Nacional del Ecuador"}]},{"@type":"WebSite","@id":"https:\/\/test.intlweloveu.org\/ko\/#website","url":"https:\/\/test.intlweloveu.org\/ko\/","name":"Fundaci\u00f3n Internacional WeLoveU","description":"El Amor de la Madre al Mundo Entero","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.intlweloveu.org\/ko\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/test.intlweloveu.org\/ko\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131","name":"l ss"}]}},"_links":{"self":[{"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/42043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/comments?post=42043"}],"version-history":[{"count":3,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/42043\/revisions"}],"predecessor-version":[{"id":42047,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/42043\/revisions\/42047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/media\/42292"}],"wp:attachment":[{"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/media?parent=42043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/categories?post=42043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/test.intlweloveu.org\/es\/wp-json\/wp\/v2\/tags?post=42043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}